{"id":3366,"date":"2022-06-05T23:17:14","date_gmt":"2022-06-06T02:17:14","guid":{"rendered":"https:\/\/folhaespirita.com.br.br\/jornal\/?p=3366"},"modified":"2026-01-23T20:17:14","modified_gmt":"2026-01-23T23:17:14","slug":"a-maior-pessoa-que-ja-conheci-na-minha-vida","status":"publish","type":"post","link":"https:\/\/folhaespirita.com.br\/en\/2022\/06\/05\/a-maior-pessoa-que-ja-conheci-na-minha-vida\/","title":{"rendered":"The greatest person I've ever met in my life"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"762\" height=\"800\" src=\"https:\/\/folhaespirita.com.br\/wp-content\/uploads\/2022\/06\/chico.jpg\" alt=\"\" class=\"wp-image-3376\" srcset=\"https:\/\/folhaespirita.com.br\/wp-content\/uploads\/2022\/06\/chico.jpg 762w, https:\/\/folhaespirita.com.br\/wp-content\/uploads\/2022\/06\/chico-286x300.jpg 286w\" sizes=\"(max-width: 762px) 100vw, 762px\" \/><\/figure>\n\n\n\n<p>N\u00e3o me lembro exatamente quantos anos tinha na primeira vez que vi o Chico, devia ter uns 6 ou 7 anos. Meu pai e minha m\u00e3e (Jos\u00e9 Freitas Nobre e Marlene Nobre) participavam das a\u00e7\u00f5es e dos trabalhos no Grupo Esp\u00edrita da Prece. Como eu e meu irm\u00e3o, Marcos, \u00e9ramos pequenos, t\u00ednhamos que ficar sempre com algu\u00e9m no carro ou na parte de fora da casa. Recordo que era muito impactante para mim um mar de gente dentro e fora da casa. Lembro-me de ir ao meio das pessoas at\u00e9 uma das janelas da resid\u00eancia e ver as pessoas sentadas \u00e0 mesa, mantendo o teor vibrat\u00f3rio, e o Chico com os olhos fechados, uma m\u00e3o na testa, o l\u00e1pis na outra, o papel sobre a mesa e escrevendo.<\/p>\n\n\n\n<p>Mas o Chico j\u00e1 era presente na minha vida muito antes dessa lembran\u00e7a: ele foi o respons\u00e1vel pela minha reencarna\u00e7\u00e3o. Minha m\u00e3e era estudante de Medicina na Universidade Federal de Uberaba e secretariou o Chico durante o per\u00edodo dela na universidade e resid\u00eancia, participando dos trabalhos sociais e tamb\u00e9m do Grupo Esp\u00edrita da Prece. O meu pai, \u00e0 \u00e9poca, era vice-prefeito de S\u00e3o Paulo e conheceu o Sp\u00e1rtaco Ghilardi, presidente do grupo esp\u00edrita Batu\u00edra, em S\u00e3o Paulo (SP). Ele se encantou pelo trabalho deles e contou que tinha uma enorme curiosidade de conhecer o Chico Xavier, \u201cessa figura humana que nem parece humana\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>RUMO A UBERABA<\/strong><\/h2>\n\n\n\n<p>Sp\u00e1rtaco ent\u00e3o levou meu pai para Uberaba (MG). Eles ficaram na fila horas e horas, e quando o meu pai estava se aproximando do Chico, reparou que ele o olhava, dava risada e balan\u00e7ava a cabe\u00e7a. Meu pai imaginou que talvez ele o tivesse reconhecido de alguma entrevista em algum ve\u00edculo. Ao se aproximar do Chico, ele o chamou pelo nome: \u201cdoutor Freitas Nobre, eu estava o aguardando. Estou aqui com Emmanuel e ele est\u00e1 dizendo que eu tenho de apresent\u00e1-los, doutor Freitas, doutora Marlene, doutora Marlene, doutor Freitas\u201d. Minha m\u00e3e estava sentada ao lado do Chico. Foi assim que se conheceram e logo come\u00e7aram a namorar.<\/p>\n\n\n\n<p>Read also: <a href=\"https:\/\/folhaespirita.com.br\/en\/como-chico-vivia-intensamente-o-espirito-do-natal\/\" target=\"_blank\" rel=\"noreferrer noopener\">How intensely Chico lived the spirit of Christmas<\/a><\/p>\n\n\n\n<p>Do meu conv\u00edvio com o Chico, lembro-me de muita coisa. Ele adorava os cachorros dele, e eles eram loucos por ele, ficavam no p\u00e9, no colo. Depois que terminavam os trabalhos do <strong><a href=\"http:\/\/grupoespiritadaprece.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo Esp\u00edrita da Prece<\/a><\/strong>, sempre tarde da noite, ele convidava algumas pessoas pr\u00f3ximas para irem para a casa dele para tomar uma sopa, um ch\u00e1 ou um caf\u00e9 com bolo e ficava conversando at\u00e9 tarde da madrugada. Todos sempre davam muita risada porque o Chico tinha um humor muito fino, falava cada coisa gostosa.<\/p>\n\n\n\n<p>Uma noite quando crian\u00e7a, com muito sono, o Chico falou para eu me deitar no quarto dele, que ficava de frente para a mesa onde todos estavam conversando. Deitei-me na cama de lado, para continuar olhando o Chico. Ele ent\u00e3o muito do danado virou e disse: \u201cvoc\u00eas n\u00e3o acreditam o que aconteceu comigo ontem \u00e0 noite: alguns credores do passado vieram na minha cama me pegar enquanto estava dormindo\u201d. Mesmo quase dormindo, ao ouvir aquilo, dei um pulo e corri para a sala. Da\u00ed foi uma risada geral. Nunca soube se isso era real ou se o Chico estava fazendo brincadeira comigo.<\/p>\n\n\n\n<p>Nunca vi o Chico triste, chateado, fazendo cara de emburrado. Mesmo quando estava muito doente, n\u00e3o reclamava, estava sempre com um sorriso, sempre de bom humor, era impressionante. Outra coisa que era muito marcante para mim era que toda vez que sa\u00eda da casa dele, eu parava na porta da cozinha, olhava para tr\u00e1s e ele estava sentado na cadeira dele e me mandava um beijo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-filme-sobre-o-m-dium\">Filme sobre o m\u00e9dium<\/h3>\n\n\n\n<p>Quero dividir nesta minha singela homenagem ao Chico algo que poucos sabem. Estava no meu escrit\u00f3rio um dia perto da hora do almo\u00e7o, toca o meu telefone e vejo que \u00e9 um amigo da minha fam\u00edlia, o Oceano Vieira de Mello. Ele estava almo\u00e7ando com Bruno Wainer, ent\u00e3o presidente da Paramount Filmes no Brasil, e o estava convencendo a fazer um filme sobre a vida do Chico. E eles queriam que eu falasse com o Eur\u00edpedes, filho do Chico (e eu digo filho do Chico porque ouvi a vida inteira ele o chamar de filho e trat\u00e1-lo como tal) para que ele desse a autoriza\u00e7\u00e3o. Eur\u00edpedes estava relutante, e o convenci a nos receber em Uberaba para falarmos sobre o projeto.<\/p>\n\n\n\n<p>Read also: <a href=\"https:\/\/folhaespirita.com.br\/en\/relacao-das-obras-de-chico-xavier\/\" target=\"_blank\" rel=\"noreferrer noopener\">List of Chico Xavier's works<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>UMA MENSAGEM DO PLANO MAIOR<\/strong><\/h2>\n\n\n\n<p>No voo de volta, me bateu um enorme desespero. Comecei a pensar sobre a responsabilidade e o risco de ser o instrumento de um filme de uma pessoa que voc\u00ea ama e no final a obra retrat\u00e1-lo de uma forma n\u00e3o t\u00e3o positiva ou realista. N\u00e3o comentei com ningu\u00e9m, mas estava decidido a falar com o Eur\u00edpedes quando pousasse em S\u00e3o Paulo e pedir para ele n\u00e3o aprovar a obra. Cheguei em casa, esqueci de ligar para ele. No dia seguinte, fui trabalhar, tive um dia muito ocupado e n\u00e3o consegui ligar para o Eur\u00edpedes. Era tamb\u00e9m o meu dia de ir ao <strong><a href=\"https:\/\/web.facebook.com\/Grupo-Esp%C3%ADrita-Cairbar-Schutel-575146999239475\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo Esp\u00edrita Cairbar Schutel<\/a><\/strong> para participar dos trabalhos medi\u00fanicos. Na comunica\u00e7\u00e3o no t\u00e9rmino da sess\u00e3o, quando geralmente recebemos uma mensagem de um Esp\u00edrito mais elevado, todos os presentes muito concentrados, aquele sil\u00eancio absoluto, e ouvimos o seguinte: \u201cquerido amigo Marcelo, Jesus me permitiu vir aqui falar com voc\u00ea para acalmar seu cora\u00e7\u00e3o. Somos n\u00f3s que estamos por tr\u00e1s do filme, voc\u00ea \u00e9 um instrumento. Voc\u00ea fez muito bem aquilo que n\u00f3s precis\u00e1vamos que tivesse feito e n\u00f3s daremos continuidade a esse projeto, porque \u00e9 um projeto da espiritualidade. Receba um grande abra\u00e7o fraterno e agradecido do seu amigo Vanucci (Augusto C\u00e9sar Vanucci, ator, produtor e diretor de televis\u00e3o)\u201d. <\/p>\n\n\n\n<p>Chico Xavier foi a maior pessoa que conheci na minha vida. Quando penso nele, em seu compromisso existencial, vejo o quanto sou pequeno. Chico exemplificou, n\u00e3o julgava, n\u00e3o tinha nenhuma express\u00e3o triste ou negativa. Enxergava todo mundo como verdadeira irm\u00e3 e verdadeiro irm\u00e3o, com muito carinho, acolhendo a todos. Chico era o amor na sua ess\u00eancia, fazia exatamente tudo aquilo que pregava, assim como Jesus.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: 51 - Chico Xavier and the planetary transition - Interview with Geraldinho Lemos Neto - episode 3\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/6lcBHicqsOmCGziJZOR4Cw?si=e53594bcf9d04d72&amp;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p> Marcelo Nobre, son of Marlene Nobre, talks about Chico Xavier's influence on his life. \u201cChico was responsible for my reincarnation\u201d.<\/p>","protected":false},"author":40,"featured_media":3387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"edicoes":[494],"class_list":["post-3366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","edicoes-579-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/posts\/3366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/comments?post=3366"}],"version-history":[{"count":5,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/posts\/3366\/revisions"}],"predecessor-version":[{"id":3407,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/posts\/3366\/revisions\/3407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/media\/3387"}],"wp:attachment":[{"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/media?parent=3366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/categories?post=3366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/tags?post=3366"},{"taxonomy":"edicoes","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/en\/wp-json\/wp\/v2\/edicoes?post=3366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}