{"id":5249,"date":"2023-12-03T12:53:48","date_gmt":"2023-12-03T15:53:48","guid":{"rendered":"https:\/\/folhaespirita.com.br.br\/jornal\/?p=5249"},"modified":"2026-01-23T20:17:08","modified_gmt":"2026-01-23T23:17:08","slug":"nepe-brasil","status":"publish","type":"post","link":"https:\/\/folhaespirita.com.br\/es\/2023\/12\/03\/nepe-brasil\/","title":{"rendered":"Nepe-Brasil"},"content":{"rendered":"<h1 class=\"wp-block-heading\">N\u00facleo de Estudo de Pesquisa do Evangelho<\/h1>\n\n\n\n<h1 class=\"wp-block-heading\"><a href=\"http:\/\/www.nepebrasil.org\">http:\/\/www.nepebrasil.org<\/a><\/h1>\n\n\n\n<p>O NEPE-Brasil constitui uma rede de NEPEs espalhados por todo o territ\u00f3rio brasileiro que visa unir esfor\u00e7os para a melhor compreens\u00e3o dos ensinos do Cristo \u00e0 luz do Espiritismo, conforme a m\u00e1xima do benfeitor espiritual Emmanuel: \u201cJesus, a porta. Kardec, a chave\u201d.<\/p>\n\n\n\n<p>\u201cSe outros povos atestaram o progresso, pelas express\u00f5es materializadas e transit\u00f3rias, o Brasil ter\u00e1 a sua express\u00e3o imortal na vida do Esp\u00edrito, representando a fonte de um pensamento novo, sem as ideologias de separatividade, e inundando todos os campos das atividades humanas com uma nova luz\u201d (Emmanuel, <em>Brasil, cora\u00e7\u00e3o do mundo, p\u00e1tria do Evangelho<\/em>).<\/p>","protected":false},"excerpt":{"rendered":"<p>N\u00facleo de Estudo de Pesquisa do Evangelho http:\/\/www.nepebrasil.org O NEPE-Brasil constitui uma rede de NEPEs espalhados por todo o territ\u00f3rio brasileiro que visa unir esfor\u00e7os para a melhor compreens\u00e3o dos ensinos do Cristo \u00e0 luz do Espiritismo, conforme a m\u00e1xima do benfeitor espiritual Emmanuel: \u201cJesus, a porta. Kardec, a chave\u201d. \u201cSe outros povos atestaram o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24],"tags":[],"edicoes":[591],"class_list":["post-5249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espiritismo-na-web","edicoes-597-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts\/5249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/comments?post=5249"}],"version-history":[{"count":1,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts\/5249\/revisions"}],"predecessor-version":[{"id":5251,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts\/5249\/revisions\/5251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/media\/5250"}],"wp:attachment":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/media?parent=5249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/categories?post=5249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/tags?post=5249"},{"taxonomy":"edicoes","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/edicoes?post=5249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}