{"id":888,"date":"2021-01-05T00:22:59","date_gmt":"2021-01-05T03:22:59","guid":{"rendered":"https:\/\/folhaespirita.com.br.br\/jornal\/?p=888"},"modified":"2026-01-23T20:17:21","modified_gmt":"2026-01-23T23:17:21","slug":"vida-apos-a-morte-e-tema-de-documentario-da-netflix","status":"publish","type":"post","link":"https:\/\/folhaespirita.com.br\/es\/2021\/01\/05\/vida-apos-a-morte-e-tema-de-documentario-da-netflix\/","title":{"rendered":"La vida despu\u00e9s de la muerte es el tema de un documental de Netflix"},"content":{"rendered":"<p>O que acontece depois da morte? O que significa morrer? A morte \u00e9 o fim da nossa exist\u00eancia? Todas essas quest\u00f5es s\u00e3o abordadas na s\u00e9rie documental da <a href=\"https:\/\/www.netflix.com\/br\/title\/80998853?trkid=13747225&amp;s=a&amp;t=cp\">Netflix<\/a> <em>A vida ap\u00f3s a morte<\/em>, que estreia em 6 de janeiro. Baseado no<em> best-seller <\/em>da jornalista Leslie Kean, apresenta, ao longo dos epis\u00f3dios, entrevistas de cientistas, m\u00e9diuns, especialistas em paranormalidade e psiquiatras infantis para explorar experi\u00eancias de quase morte, sess\u00f5es esp\u00edritas e outras comunica\u00e7\u00f5es p\u00f3s-morte e lembran\u00e7as de vidas passadas. Assista ao trailer oficial.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"VIDA AP\u00d3S A MORTE (trailer) s\u00e9rie document\u00e1rio da Netflix\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/YkE5kn_eRCU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>O que acontece depois da morte? O que significa morrer? A morte \u00e9 o fim da nossa exist\u00eancia? Todas essas quest\u00f5es s\u00e3o abordadas na s\u00e9rie documental da Netflix A vida ap\u00f3s a morte, que estreia em 6 de janeiro. Baseado no best-seller da jornalista Leslie Kean, apresenta, ao longo dos epis\u00f3dios, entrevistas de cientistas, m\u00e9diuns, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[179],"edicoes":[195],"class_list":["post-888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lancamento","tag-eqm-experiencia-de-quase-morte","edicoes-562-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts\/888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/comments?post=888"}],"version-history":[{"count":1,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts\/888\/revisions"}],"predecessor-version":[{"id":891,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/posts\/888\/revisions\/891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/media\/950"}],"wp:attachment":[{"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/media?parent=888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/categories?post=888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/tags?post=888"},{"taxonomy":"edicoes","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/es\/wp-json\/wp\/v2\/edicoes?post=888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}