{"id":7965,"date":"2025-03-10T23:39:52","date_gmt":"2025-03-11T02:39:52","guid":{"rendered":"https:\/\/folhaespirita.com.br.br\/jornal\/?p=7965"},"modified":"2026-01-23T20:17:03","modified_gmt":"2026-01-23T23:17:03","slug":"manual-do-evangelizador","status":"publish","type":"post","link":"https:\/\/folhaespirita.com.br\/pt\/2025\/03\/10\/manual-do-evangelizador\/","title":{"rendered":"Manual do evangelizador"},"content":{"rendered":"<h1 class=\"wp-block-heading\"><a href=\"http:\/\/www.manualdoevangelizador.com.br\">www.manualdoevangelizador.com.br<\/a><\/h1>\n\n\n\n<p>Somos evangelizadores e gostar\u00edamos de compartilhar nossas produ\u00e7\u00f5es nessa maravilhosa tarefa de espargir os ensinos de Jesus. Nosso objetivo \u00e9 ampliar o estudo e a an\u00e1lise da Evangeliza\u00e7\u00e3o e do uso da did\u00e1tica como ferramenta no processo de ensino-aprendizagem.<\/p>\n\n\n\n<p>Os irm\u00e3os perceber\u00e3o que se trata de material simples, composto de metodologia participativa, resultado de reflex\u00f5es, pesquisas e aplica\u00e7\u00f5es que contribu\u00edram em nossa tarefa. Apresentamos um programa que segue a linha da educa\u00e7\u00e3o dos sentimentos. Com base no Evangelho de Jesus \u00e0 luz da Doutrina Esp\u00edrita, propomos atividades construtivas para que o evangelizando se envolva nos conceitos e reelabore-os para aplica\u00e7\u00e3o em seu dia a dia.<\/p>\n\n\n\n<p>Esse site \u00e9 uma constru\u00e7\u00e3o coletiva, sem fins lucrativos.<\/p>\n\n\n\n<p>Cooperemos com Jesus, evangelizando.<\/p>","protected":false},"excerpt":{"rendered":"<p>www.manualdoevangelizador.com.br Somos evangelizadores e gostar\u00edamos de compartilhar nossas produ\u00e7\u00f5es nessa maravilhosa tarefa de espargir os ensinos de Jesus. Nosso objetivo \u00e9 ampliar o estudo e a an\u00e1lise da Evangeliza\u00e7\u00e3o e do uso da did\u00e1tica como ferramenta no processo de ensino-aprendizagem. Os irm\u00e3os perceber\u00e3o que se trata de material simples, composto de metodologia participativa, resultado de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24],"tags":[],"edicoes":[636],"class_list":["post-7965","post","type-post","status-publish","format-standard","hentry","category-espiritismo-na-web","edicoes-marco-de-2025"],"acf":[],"_links":{"self":[{"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/posts\/7965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/comments?post=7965"}],"version-history":[{"count":1,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/posts\/7965\/revisions"}],"predecessor-version":[{"id":7966,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/posts\/7965\/revisions\/7966"}],"wp:attachment":[{"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/media?parent=7965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/categories?post=7965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/tags?post=7965"},{"taxonomy":"edicoes","embeddable":true,"href":"https:\/\/folhaespirita.com.br\/pt\/wp-json\/wp\/v2\/edicoes?post=7965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}